{"id":54,"count":5,"description":"","link":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/","name":"Chile","slug":"chile-es","taxonomy":"case-study-category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chile Archives - Horizonte Tours<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chile Archives - Horizonte Tours\" \/>\n<meta property=\"og:url\" content=\"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Horizonte Tours\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/\",\"url\":\"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/\",\"name\":\"Chile Archives - Horizonte Tours\",\"isPartOf\":{\"@id\":\"https:\/\/horizonte-tours.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/horizonte-tours.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/horizonte-tours.com\/#website\",\"url\":\"https:\/\/horizonte-tours.com\/\",\"name\":\"Horizonte Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/horizonte-tours.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/horizonte-tours.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/horizonte-tours.com\/#organization\",\"name\":\"Horizonte Tours\",\"url\":\"https:\/\/horizonte-tours.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/horizonte-tours.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/horizonte-tours.com\/wp-content\/uploads\/2021\/08\/logo_horizonte_tours_dark.png\",\"contentUrl\":\"https:\/\/horizonte-tours.com\/wp-content\/uploads\/2021\/08\/logo_horizonte_tours_dark.png\",\"width\":771,\"height\":297,\"caption\":\"Horizonte Tours\"},\"image\":{\"@id\":\"https:\/\/horizonte-tours.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chile Archives - Horizonte Tours","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Chile Archives - Horizonte Tours","og_url":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/","og_site_name":"Horizonte Tours","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/","url":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/","name":"Chile Archives - Horizonte Tours","isPartOf":{"@id":"https:\/\/horizonte-tours.com\/#website"},"breadcrumb":{"@id":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/horizonte-tours.com\/es\/case-study-category\/chile-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/horizonte-tours.com\/es\/"},{"@type":"ListItem","position":2,"name":"Chile"}]},{"@type":"WebSite","@id":"https:\/\/horizonte-tours.com\/#website","url":"https:\/\/horizonte-tours.com\/","name":"Horizonte Tours","description":"","publisher":{"@id":"https:\/\/horizonte-tours.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/horizonte-tours.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/horizonte-tours.com\/#organization","name":"Horizonte Tours","url":"https:\/\/horizonte-tours.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/horizonte-tours.com\/#\/schema\/logo\/image\/","url":"https:\/\/horizonte-tours.com\/wp-content\/uploads\/2021\/08\/logo_horizonte_tours_dark.png","contentUrl":"https:\/\/horizonte-tours.com\/wp-content\/uploads\/2021\/08\/logo_horizonte_tours_dark.png","width":771,"height":297,"caption":"Horizonte Tours"},"image":{"@id":"https:\/\/horizonte-tours.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/horizonte-tours.com\/es\/wp-json\/wp\/v2\/case-study-category\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/horizonte-tours.com\/es\/wp-json\/wp\/v2\/case-study-category"}],"about":[{"href":"https:\/\/horizonte-tours.com\/es\/wp-json\/wp\/v2\/taxonomies\/case-study-category"}]}}